{"id":75,"count":2,"description":"","link":"https:\/\/www.albert-schweitzer-schu-le.de\/wp-neu\/mec-category\/schul-termine\/","name":"schul. Termine","slug":"schul-termine","taxonomy":"mec_category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.albert-schweitzer-schu-le.de\/wp-neu\/wp-json\/wp\/v2\/mec_category\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albert-schweitzer-schu-le.de\/wp-neu\/wp-json\/wp\/v2\/mec_category"}],"about":[{"href":"https:\/\/www.albert-schweitzer-schu-le.de\/wp-neu\/wp-json\/wp\/v2\/taxonomies\/mec_category"}],"wp:post_type":[{"href":"https:\/\/www.albert-schweitzer-schu-le.de\/wp-neu\/wp-json\/wp\/v2\/mec-events?mec_category=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}